{"id":59,"count":2,"description":"","link":"https:\/\/leadell.lt\/en\/team-practice-area\/media\/","name":"Media","slug":"media","taxonomy":"team_practice_area","parent":0,"meta":[],"acf":{"link":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Media Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leadell.lt\/en\/team-practice-area\/media\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Media Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leadell.lt\/en\/team-practice-area\/media\/\" \/>\n<meta property=\"og:site_name\" content=\"LEADELL Bal\u010di\u016bnas &amp; Grajauskas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/leadell.lt\\\/en\\\/team-practice-area\\\/media\\\/\",\"url\":\"https:\\\/\\\/leadell.lt\\\/en\\\/team-practice-area\\\/media\\\/\",\"name\":\"Media Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadell.lt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leadell.lt\\\/en\\\/team-practice-area\\\/media\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leadell.lt\\\/en\\\/team-practice-area\\\/media\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leadell.lt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Media\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leadell.lt\\\/#website\",\"url\":\"https:\\\/\\\/leadell.lt\\\/\",\"name\":\"LEADELL Bal\u010di\u016bnas &amp; Grajauskas\",\"description\":\"We are among leading law firms in the Baltic countries providing services to business clients\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leadell.lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Media Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leadell.lt\/en\/team-practice-area\/media\/","og_locale":"en_US","og_type":"article","og_title":"Media Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas","og_url":"https:\/\/leadell.lt\/en\/team-practice-area\/media\/","og_site_name":"LEADELL Bal\u010di\u016bnas &amp; Grajauskas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/leadell.lt\/en\/team-practice-area\/media\/","url":"https:\/\/leadell.lt\/en\/team-practice-area\/media\/","name":"Media Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas","isPartOf":{"@id":"https:\/\/leadell.lt\/#website"},"breadcrumb":{"@id":"https:\/\/leadell.lt\/en\/team-practice-area\/media\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/leadell.lt\/en\/team-practice-area\/media\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leadell.lt\/en\/"},{"@type":"ListItem","position":2,"name":"Media"}]},{"@type":"WebSite","@id":"https:\/\/leadell.lt\/#website","url":"https:\/\/leadell.lt\/","name":"LEADELL Bal\u010di\u016bnas &amp; Grajauskas","description":"We are among leading law firms in the Baltic countries providing services to business clients","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leadell.lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/leadell.lt\/en\/wp-json\/wp\/v2\/team_practice_area\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadell.lt\/en\/wp-json\/wp\/v2\/team_practice_area"}],"about":[{"href":"https:\/\/leadell.lt\/en\/wp-json\/wp\/v2\/taxonomies\/team_practice_area"}],"wp:post_type":[{"href":"https:\/\/leadell.lt\/en\/wp-json\/wp\/v2\/team?team_practice_area=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}