{"id":234,"count":3,"description":"","link":"https:\/\/leadell.lt\/en\/team-position\/associate-partners\/","name":"Associate partners","slug":"associate-partners","taxonomy":"team_position","parent":0,"meta":[],"acf":{"order_number":"2"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Associate partners Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leadell.lt\/en\/team-position\/associate-partners\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Associate partners Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leadell.lt\/en\/team-position\/associate-partners\/\" \/>\n<meta property=\"og:site_name\" content=\"LEADELL Bal\u010di\u016bnas &amp; Grajauskas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/leadell.lt\\\/en\\\/team-position\\\/associate-partners\\\/\",\"url\":\"https:\\\/\\\/leadell.lt\\\/en\\\/team-position\\\/associate-partners\\\/\",\"name\":\"Associate partners Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadell.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leadell.lt\\\/en\\\/team-position\\\/associate-partners\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leadell.lt\\\/en\\\/team-position\\\/associate-partners\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leadell.lt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Associate partners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leadell.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/leadell.lt\\\/en\\\/\",\"name\":\"LEADELL Bal\u010di\u016bnas &amp; Grajauskas\",\"description\":\"We are among leading law firms in the Baltic countries providing services to business clients\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leadell.lt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Associate partners Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leadell.lt\/en\/team-position\/associate-partners\/","og_locale":"en_US","og_type":"article","og_title":"Associate partners Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas","og_url":"https:\/\/leadell.lt\/en\/team-position\/associate-partners\/","og_site_name":"LEADELL Bal\u010di\u016bnas &amp; Grajauskas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/leadell.lt\/en\/team-position\/associate-partners\/","url":"https:\/\/leadell.lt\/en\/team-position\/associate-partners\/","name":"Associate partners Archives - LEADELL Bal\u010di\u016bnas &amp; Grajauskas","isPartOf":{"@id":"https:\/\/leadell.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/leadell.lt\/en\/team-position\/associate-partners\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/leadell.lt\/en\/team-position\/associate-partners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leadell.lt\/en\/"},{"@type":"ListItem","position":2,"name":"Associate partners"}]},{"@type":"WebSite","@id":"https:\/\/leadell.lt\/en\/#website","url":"https:\/\/leadell.lt\/en\/","name":"LEADELL Bal\u010di\u016bnas &amp; Grajauskas","description":"We are among leading law firms in the Baltic countries providing services to business clients","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leadell.lt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/leadell.lt\/en\/wp-json\/wp\/v2\/team_position\/234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadell.lt\/en\/wp-json\/wp\/v2\/team_position"}],"about":[{"href":"https:\/\/leadell.lt\/en\/wp-json\/wp\/v2\/taxonomies\/team_position"}],"wp:post_type":[{"href":"https:\/\/leadell.lt\/en\/wp-json\/wp\/v2\/team?team_position=234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}